{"id":6228,"date":"2025-12-26T11:09:49","date_gmt":"2025-12-26T11:09:49","guid":{"rendered":"https:\/\/cpyts.com\/?p=6228"},"modified":"2025-12-30T13:13:50","modified_gmt":"2025-12-30T13:13:50","slug":"hello-world-4","status":"publish","type":"post","link":"https:\/\/cpyts.com\/zh\/hello-world-4\/","title":{"rendered":"Hello world!"},"content":{"rendered":"<p>\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u60a8\u53ef\u4ee5\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\uff01<\/p>","protected":false},"excerpt":{"rendered":"<p>\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\u5427\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\u5427\uff01\u6b22\u8fce\u4f7f\u7528WordPress\u3002\u8fd9\u662f\u60a8\u7684\u9996\u7bc7\u6587\u7ae0\u3002\u7f16\u8f91\u6216\u5220\u9664\u5b83\uff0c\u7136\u540e\u5f00\u59cb\u64b0\u5199\u5427\uff01<\/p>","protected":false},"author":1,"featured_media":4506,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6228","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","travel-monster-post","latest_post"],"jetpack_featured_media_url":"https:\/\/cpyts.com\/wp-content\/uploads\/2022\/11\/annapurna.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/cpyts.com\/zh\/wp-json\/wp\/v2\/posts\/6228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cpyts.com\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cpyts.com\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cpyts.com\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cpyts.com\/zh\/wp-json\/wp\/v2\/comments?post=6228"}],"version-history":[{"count":1,"href":"https:\/\/cpyts.com\/zh\/wp-json\/wp\/v2\/posts\/6228\/revisions"}],"predecessor-version":[{"id":6233,"href":"https:\/\/cpyts.com\/zh\/wp-json\/wp\/v2\/posts\/6228\/revisions\/6233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cpyts.com\/zh\/wp-json\/wp\/v2\/media\/4506"}],"wp:attachment":[{"href":"https:\/\/cpyts.com\/zh\/wp-json\/wp\/v2\/media?parent=6228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cpyts.com\/zh\/wp-json\/wp\/v2\/categories?post=6228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cpyts.com\/zh\/wp-json\/wp\/v2\/tags?post=6228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}